{"id":10123,"date":"2020-09-23T17:54:25","date_gmt":"2020-09-23T15:54:25","guid":{"rendered":"https:\/\/www.bouquetdalella.com\/producte\/bouquet-dalella-garnaxa-negra-2022\/"},"modified":"2026-05-12T03:25:28","modified_gmt":"2026-05-12T01:25:28","slug":"bouquet-dalella-garnaxa-negra-2024","status":"publish","type":"product","link":"https:\/\/www.bouquetdalella.com\/en\/producte\/bouquet-dalella-garnaxa-negra-2024\/","title":{"rendered":"Bouquet d&#8217;Alella Garnaxa Negra 2024"},"content":{"rendered":"\t\t<div data-elementor-type=\"product-post\" data-elementor-id=\"10123\" class=\"elementor elementor-10123 elementor-6321\" data-elementor-post-type=\"product\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-673a4c7f elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"673a4c7f\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-1bdd4b80\" data-id=\"1bdd4b80\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-7ecc19ad tab_zone elementor-tabs-view-horizontal elementor-widget elementor-widget-tabs\" data-id=\"7ecc19ad\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"tabs.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-tabs\">\n\t\t\t<div class=\"elementor-tabs-wrapper\" role=\"tablist\" >\n\t\t\t\t\t\t\t\t\t<div id=\"elementor-tab-title-2121\" class=\"elementor-tab-title elementor-tab-desktop-title\" aria-selected=\"true\" data-tab=\"1\" role=\"tab\" tabindex=\"0\" aria-controls=\"elementor-tab-content-2121\" aria-expanded=\"false\">Elaboration<\/div>\n\t\t\t\t\t\t\t\t\t<div id=\"elementor-tab-title-2122\" class=\"elementor-tab-title elementor-tab-desktop-title\" aria-selected=\"false\" data-tab=\"2\" role=\"tab\" tabindex=\"-1\" aria-controls=\"elementor-tab-content-2122\" aria-expanded=\"false\">Tasting note<\/div>\n\t\t\t\t\t\t\t\t\t<div id=\"elementor-tab-title-2123\" class=\"elementor-tab-title elementor-tab-desktop-title\" aria-selected=\"false\" data-tab=\"3\" role=\"tab\" tabindex=\"-1\" aria-controls=\"elementor-tab-content-2123\" aria-expanded=\"false\">FREE SHIPPING from 60 \u20ac (valid in the Spanish Peninsula)<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t<div class=\"elementor-tabs-content-wrapper\" role=\"tablist\" aria-orientation=\"vertical\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-tab-title elementor-tab-mobile-title\" aria-selected=\"true\" data-tab=\"1\" role=\"tab\" tabindex=\"0\" aria-controls=\"elementor-tab-content-2121\" aria-expanded=\"false\">Elaboration<\/div>\n\t\t\t\t\t<div id=\"elementor-tab-content-2121\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"1\" role=\"tabpanel\" aria-labelledby=\"elementor-tab-title-2121\" tabindex=\"0\" hidden=\"false\"><p>Red wine from a local variety, organic farming and old vineyards. Manual harvest in 15 kg boxes and a strict selection of grapes in the vineyard. The grapes are then refrigerated in a cold room for a few hours to obtain aromatic precursors. Then they are destemmed and the 20% of them are given a carbonic maceration, while the rest goes into a long maceration with the skins, pumping-over the must to extract the coloring matter from skins, while it ferments. It is then gently pressed and finally malolactic fermentation is carried out.<\/p><p>\u00a0<\/p><p>Still red wine made of 100% Grenache. Limited production, 3662 bottles. With an alcohol content of 13.5% vol.<\/p><\/div>\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-tab-title elementor-tab-mobile-title\" aria-selected=\"false\" data-tab=\"2\" role=\"tab\" tabindex=\"-1\" aria-controls=\"elementor-tab-content-2122\" aria-expanded=\"false\">Tasting note<\/div>\n\t\t\t\t\t<div id=\"elementor-tab-content-2122\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"2\" role=\"tabpanel\" aria-labelledby=\"elementor-tab-title-2122\" tabindex=\"0\" hidden=\"hidden\"><p style=\"text-align: left;\"><em><b>Look:<\/b><\/em> it has a bright red colour and pinkish borders.\u00a0<\/p><p style=\"text-align: left;\"><em><b>Smell:<\/b><\/em> medium intensity. Pleasant fresh aromas of red berries, wild strawberries, raspberries, plums and soft hints of citrus orange peel. A clear varietal example from the Mediterranean area.<\/p><p style=\"text-align: left;\"><em><b>Taste:<\/b><\/em> sharp and a light mouthfeel, it has hints of fruit as the skin of red plums, delicate finish with a certain warmth.<\/p><p style=\"text-align: left;\"><em><b>It pairs well<\/b> <strong>with<\/strong><\/em> soft cheeses, cold meats, p\u00e2t\u00e9s (also vegetable), and cold soups. We recommend serving it between 14\u00baC and 16\u00baC\u00ba<\/p><\/div>\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-tab-title elementor-tab-mobile-title\" aria-selected=\"false\" data-tab=\"3\" role=\"tab\" tabindex=\"-1\" aria-controls=\"elementor-tab-content-2123\" aria-expanded=\"false\">FREE SHIPPING from 60 \u20ac (valid in the Spanish Peninsula)<\/div>\n\t\t\t\t\t<div id=\"elementor-tab-content-2123\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"3\" role=\"tabpanel\" aria-labelledby=\"elementor-tab-title-2123\" tabindex=\"0\" hidden=\"hidden\"><p><strong>FREE SHIPPING<\/strong><\/p><ul><li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">If your order is placed within the national scope and exceeds 60 euros (VAT included) you will have free shipping. It does not include outside the peninsula.<br \/><br \/><\/span><\/li><\/ul><p><strong>DELIVERY TIME AND SHIPPING COSTS<\/strong><\/p><ul><li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">Once the order has been placed and accepted, the delivery time will be 2 to 4 working days from the payment of the purchase.<\/span><\/li><li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">Orders are sent via courier service.<\/span><\/li><li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">Delivery will be made to the address provided during the ordering process.<\/span><\/li><\/ul><\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Red wine made of Grenache. Light and fresh, it doesn&#8217;t really need accompaniment although it is a great wine for reencounters with friends, enjoy a drink in the afternoon or to have with some tapas. Limited production of 3662 bottles.<\/p>\n","protected":false},"featured_media":1737,"template":"","meta":[],"product_brand":[],"product_cat":[392],"product_tag":[349],"class_list":["post-10123","product","type-product","status-publish","has-post-thumbnail","product_cat-vins-bouquet-dalella-en","product_tag-vins-en","first","instock","taxable","shipping-taxable","purchasable","product-type-simple"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Bouquet d&#039;Alella Garnaxa Negra 2024 - Bouquet d&#039;Alella<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.bouquetdalella.com\/en\/producte\/bouquet-dalella-garnaxa-negra-2024\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Bouquet d&#039;Alella Garnaxa Negra 2024 - Bouquet d&#039;Alella\" \/>\n<meta property=\"og:description\" content=\"Red wine made of Grenache. Light and fresh, it doesn&#039;t really need accompaniment although it is a great wine for reencounters with friends, enjoy a drink in the afternoon or to have with some tapas. Limited production of 3662 bottles.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.bouquetdalella.com\/en\/producte\/bouquet-dalella-garnaxa-negra-2024\/\" \/>\n<meta property=\"og:site_name\" content=\"Bouquet d&#039;Alella\" \/>\n<meta property=\"article:modified_time\" content=\"2026-05-12T01:25:28+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.bouquetdalella.com\/wp-content\/uploads\/2023\/04\/4pA-Bouquet-dAlella-Garnatxa-Negra-1.png\" \/>\n\t<meta property=\"og:image:width\" content=\"768\" \/>\n\t<meta property=\"og:image:height\" content=\"843\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.bouquetdalella.com\\\/en\\\/producte\\\/bouquet-dalella-garnaxa-negra-2024\\\/\",\"url\":\"https:\\\/\\\/www.bouquetdalella.com\\\/en\\\/producte\\\/bouquet-dalella-garnaxa-negra-2024\\\/\",\"name\":\"Bouquet d'Alella Garnaxa Negra 2024 - Bouquet d&#039;Alella\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.bouquetdalella.com\\\/en\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.bouquetdalella.com\\\/en\\\/producte\\\/bouquet-dalella-garnaxa-negra-2024\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.bouquetdalella.com\\\/en\\\/producte\\\/bouquet-dalella-garnaxa-negra-2024\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.bouquetdalella.com\\\/wp-content\\\/uploads\\\/2023\\\/04\\\/4pA-Bouquet-dAlella-Garnatxa-Negra-1.png\",\"datePublished\":\"2020-09-23T15:54:25+00:00\",\"dateModified\":\"2026-05-12T01:25:28+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.bouquetdalella.com\\\/en\\\/producte\\\/bouquet-dalella-garnaxa-negra-2024\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.bouquetdalella.com\\\/en\\\/producte\\\/bouquet-dalella-garnaxa-negra-2024\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/www.bouquetdalella.com\\\/en\\\/producte\\\/bouquet-dalella-garnaxa-negra-2024\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.bouquetdalella.com\\\/wp-content\\\/uploads\\\/2023\\\/04\\\/4pA-Bouquet-dAlella-Garnatxa-Negra-1.png\",\"contentUrl\":\"https:\\\/\\\/www.bouquetdalella.com\\\/wp-content\\\/uploads\\\/2023\\\/04\\\/4pA-Bouquet-dAlella-Garnatxa-Negra-1.png\",\"width\":768,\"height\":843},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.bouquetdalella.com\\\/en\\\/producte\\\/bouquet-dalella-garnaxa-negra-2024\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inici\",\"item\":\"https:\\\/\\\/www.bouquetdalella.com\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Shop\",\"item\":\"https:\\\/\\\/www.bouquetdalella.com\\\/en\\\/shop\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Bouquet d&#8217;Alella Garnaxa Negra 2024\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.bouquetdalella.com\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/www.bouquetdalella.com\\\/en\\\/\",\"name\":\"Bouquet d&#039;Alella\",\"description\":\"El Celler Bouquet d\u2019Alella neix amb la clara intenci\u00f3 d\u2019explotar dues vessants diferents per\u00f2 complement\u00e0ries en el mon del vi. Per una banda, la producci\u00f3n i venda de vins ecol\u00f2gics de qualitat i per l\u2019altra la promoci\u00f3 de l\u2019enoturisme.\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.bouquetdalella.com\\\/en\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.bouquetdalella.com\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.bouquetdalella.com\\\/en\\\/#organization\",\"name\":\"Bouquet d&#039;Alella\",\"url\":\"https:\\\/\\\/www.bouquetdalella.com\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/www.bouquetdalella.com\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.bouquetdalella.com\\\/wp-content\\\/uploads\\\/2023\\\/04\\\/cropped-cropped-cropped-logo_bouquet_d_alella-2-300x53-1.png\",\"contentUrl\":\"https:\\\/\\\/www.bouquetdalella.com\\\/wp-content\\\/uploads\\\/2023\\\/04\\\/cropped-cropped-cropped-logo_bouquet_d_alella-2-300x53-1.png\",\"width\":300,\"height\":52,\"caption\":\"Bouquet d&#039;Alella\"},\"image\":{\"@id\":\"https:\\\/\\\/www.bouquetdalella.com\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Bouquet d'Alella Garnaxa Negra 2024 - Bouquet d&#039;Alella","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.bouquetdalella.com\/en\/producte\/bouquet-dalella-garnaxa-negra-2024\/","og_locale":"en_US","og_type":"article","og_title":"Bouquet d'Alella Garnaxa Negra 2024 - Bouquet d&#039;Alella","og_description":"Red wine made of Grenache. Light and fresh, it doesn't really need accompaniment although it is a great wine for reencounters with friends, enjoy a drink in the afternoon or to have with some tapas. Limited production of 3662 bottles.","og_url":"https:\/\/www.bouquetdalella.com\/en\/producte\/bouquet-dalella-garnaxa-negra-2024\/","og_site_name":"Bouquet d&#039;Alella","article_modified_time":"2026-05-12T01:25:28+00:00","og_image":[{"width":768,"height":843,"url":"https:\/\/www.bouquetdalella.com\/wp-content\/uploads\/2023\/04\/4pA-Bouquet-dAlella-Garnatxa-Negra-1.png","type":"image\/png"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.bouquetdalella.com\/en\/producte\/bouquet-dalella-garnaxa-negra-2024\/","url":"https:\/\/www.bouquetdalella.com\/en\/producte\/bouquet-dalella-garnaxa-negra-2024\/","name":"Bouquet d'Alella Garnaxa Negra 2024 - Bouquet d&#039;Alella","isPartOf":{"@id":"https:\/\/www.bouquetdalella.com\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.bouquetdalella.com\/en\/producte\/bouquet-dalella-garnaxa-negra-2024\/#primaryimage"},"image":{"@id":"https:\/\/www.bouquetdalella.com\/en\/producte\/bouquet-dalella-garnaxa-negra-2024\/#primaryimage"},"thumbnailUrl":"https:\/\/www.bouquetdalella.com\/wp-content\/uploads\/2023\/04\/4pA-Bouquet-dAlella-Garnatxa-Negra-1.png","datePublished":"2020-09-23T15:54:25+00:00","dateModified":"2026-05-12T01:25:28+00:00","breadcrumb":{"@id":"https:\/\/www.bouquetdalella.com\/en\/producte\/bouquet-dalella-garnaxa-negra-2024\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.bouquetdalella.com\/en\/producte\/bouquet-dalella-garnaxa-negra-2024\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.bouquetdalella.com\/en\/producte\/bouquet-dalella-garnaxa-negra-2024\/#primaryimage","url":"https:\/\/www.bouquetdalella.com\/wp-content\/uploads\/2023\/04\/4pA-Bouquet-dAlella-Garnatxa-Negra-1.png","contentUrl":"https:\/\/www.bouquetdalella.com\/wp-content\/uploads\/2023\/04\/4pA-Bouquet-dAlella-Garnatxa-Negra-1.png","width":768,"height":843},{"@type":"BreadcrumbList","@id":"https:\/\/www.bouquetdalella.com\/en\/producte\/bouquet-dalella-garnaxa-negra-2024\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inici","item":"https:\/\/www.bouquetdalella.com\/en\/"},{"@type":"ListItem","position":2,"name":"Shop","item":"https:\/\/www.bouquetdalella.com\/en\/shop\/"},{"@type":"ListItem","position":3,"name":"Bouquet d&#8217;Alella Garnaxa Negra 2024"}]},{"@type":"WebSite","@id":"https:\/\/www.bouquetdalella.com\/en\/#website","url":"https:\/\/www.bouquetdalella.com\/en\/","name":"Bouquet d&#039;Alella","description":"El Celler Bouquet d\u2019Alella neix amb la clara intenci\u00f3 d\u2019explotar dues vessants diferents per\u00f2 complement\u00e0ries en el mon del vi. Per una banda, la producci\u00f3n i venda de vins ecol\u00f2gics de qualitat i per l\u2019altra la promoci\u00f3 de l\u2019enoturisme.","publisher":{"@id":"https:\/\/www.bouquetdalella.com\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.bouquetdalella.com\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/www.bouquetdalella.com\/en\/#organization","name":"Bouquet d&#039;Alella","url":"https:\/\/www.bouquetdalella.com\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.bouquetdalella.com\/en\/#\/schema\/logo\/image\/","url":"https:\/\/www.bouquetdalella.com\/wp-content\/uploads\/2023\/04\/cropped-cropped-cropped-logo_bouquet_d_alella-2-300x53-1.png","contentUrl":"https:\/\/www.bouquetdalella.com\/wp-content\/uploads\/2023\/04\/cropped-cropped-cropped-logo_bouquet_d_alella-2-300x53-1.png","width":300,"height":52,"caption":"Bouquet d&#039;Alella"},"image":{"@id":"https:\/\/www.bouquetdalella.com\/en\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/www.bouquetdalella.com\/en\/wp-json\/wp\/v2\/product\/10123","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.bouquetdalella.com\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/www.bouquetdalella.com\/en\/wp-json\/wp\/v2\/types\/product"}],"version-history":[{"count":0,"href":"https:\/\/www.bouquetdalella.com\/en\/wp-json\/wp\/v2\/product\/10123\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.bouquetdalella.com\/en\/wp-json\/wp\/v2\/media\/1737"}],"wp:attachment":[{"href":"https:\/\/www.bouquetdalella.com\/en\/wp-json\/wp\/v2\/media?parent=10123"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/www.bouquetdalella.com\/en\/wp-json\/wp\/v2\/product_brand?post=10123"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/www.bouquetdalella.com\/en\/wp-json\/wp\/v2\/product_cat?post=10123"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/www.bouquetdalella.com\/en\/wp-json\/wp\/v2\/product_tag?post=10123"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}