{"id":13030,"date":"2022-10-23T14:59:21","date_gmt":"2022-10-23T12:59:21","guid":{"rendered":"https:\/\/www.bouquetdalella.com\/vins-de-vendanges-tardives-naturellement-doux\/"},"modified":"2022-10-23T15:05:10","modified_gmt":"2022-10-23T13:05:10","slug":"vins-de-vendanges-tardives-naturellement-doux","status":"publish","type":"post","link":"https:\/\/www.bouquetdalella.com\/fr\/vins-de-vendanges-tardives-naturellement-doux\/","title":{"rendered":"Vins de vendanges tardives naturellement doux"},"content":{"rendered":"<p>Aujourd&rsquo;hui cela fait une semaine que nous avons fait la derni\u00e8re entr\u00e9e de raisins pour cette ann\u00e9e 2022, ce sont nos vendanges tardives du Grenache blanc que nous utilisons pour \u00e9laborer notre pr\u00e9cieux vin doux Pur Dol\u00e7. Les vins produits en vendanges tardives sont appel\u00e9s vins naturellement doux, car dans l&rsquo;\u00e9laboration de ce vin aucun type de sucre n&rsquo;est ajout\u00e9 et son go\u00fbt sucr\u00e9 ne provient que du sucre du raisin qui a pass\u00e9 plus de temps dans le vignoble et qui est r\u00e9colt\u00e9 quand il est presque sans eau, pratiquement des raisins secs. Le pressurage de ce c\u00e9page nous donne un mo\u00fbt tr\u00e8s dense et onctueux, un sirop d&rsquo;ar\u00f4mes et de sucres naturels. Pur d\u00e9lice.<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Aujourd&rsquo;hui cela fait une semaine que nous avons fait la derni\u00e8re entr\u00e9e de raisins pour cette ann\u00e9e 2022, ce sont nos vendanges tardives du Grenache blanc que nous utilisons pour \u00e9laborer notre pr\u00e9cieux vin doux Pur Dol\u00e7. Les vins produits en vendanges tardives sont appel\u00e9s vins naturellement doux, car dans l&rsquo;\u00e9laboration de ce vin aucun [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":6266,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[189],"tags":[],"class_list":["post-13030","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-nouvelles"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Vins de vendanges tardives naturellement doux - Bouquet d&#039;Alella<\/title>\n<meta name=\"description\" content=\"Vins de vendanges tardives naturellement doux\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.bouquetdalella.com\/fr\/vins-de-vendanges-tardives-naturellement-doux\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Vins de vendanges tardives naturellement doux - Bouquet d&#039;Alella\" \/>\n<meta property=\"og:description\" content=\"Vins de vendanges tardives naturellement doux\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.bouquetdalella.com\/fr\/vins-de-vendanges-tardives-naturellement-doux\/\" \/>\n<meta property=\"og:site_name\" content=\"Bouquet d&#039;Alella\" \/>\n<meta property=\"article:published_time\" content=\"2022-10-23T12:59:21+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-10-23T13:05:10+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.bouquetdalella.com\/wp-content\/uploads\/2023\/04\/verema-bouquet-dalella.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"768\" \/>\n\t<meta property=\"og:image:height\" content=\"1024\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Bouquet Alella\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Bouquet Alella\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.bouquetdalella.com\\\/fr\\\/vins-de-vendanges-tardives-naturellement-doux\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.bouquetdalella.com\\\/fr\\\/vins-de-vendanges-tardives-naturellement-doux\\\/\"},\"author\":{\"name\":\"Bouquet Alella\",\"@id\":\"https:\\\/\\\/www.bouquetdalella.com\\\/fr\\\/#\\\/schema\\\/person\\\/726870fa22653a7029bc5a8074403803\"},\"headline\":\"Vins de vendanges tardives naturellement doux\",\"datePublished\":\"2022-10-23T12:59:21+00:00\",\"dateModified\":\"2022-10-23T13:05:10+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.bouquetdalella.com\\\/fr\\\/vins-de-vendanges-tardives-naturellement-doux\\\/\"},\"wordCount\":138,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.bouquetdalella.com\\\/fr\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.bouquetdalella.com\\\/fr\\\/vins-de-vendanges-tardives-naturellement-doux\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.bouquetdalella.com\\\/wp-content\\\/uploads\\\/2023\\\/04\\\/verema-bouquet-dalella.jpg\",\"articleSection\":[\"Nouvelles\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.bouquetdalella.com\\\/fr\\\/vins-de-vendanges-tardives-naturellement-doux\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.bouquetdalella.com\\\/fr\\\/vins-de-vendanges-tardives-naturellement-doux\\\/\",\"url\":\"https:\\\/\\\/www.bouquetdalella.com\\\/fr\\\/vins-de-vendanges-tardives-naturellement-doux\\\/\",\"name\":\"Vins de vendanges tardives naturellement doux - Bouquet d&#039;Alella\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.bouquetdalella.com\\\/fr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.bouquetdalella.com\\\/fr\\\/vins-de-vendanges-tardives-naturellement-doux\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.bouquetdalella.com\\\/fr\\\/vins-de-vendanges-tardives-naturellement-doux\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.bouquetdalella.com\\\/wp-content\\\/uploads\\\/2023\\\/04\\\/verema-bouquet-dalella.jpg\",\"datePublished\":\"2022-10-23T12:59:21+00:00\",\"dateModified\":\"2022-10-23T13:05:10+00:00\",\"description\":\"Vins de vendanges tardives naturellement doux\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.bouquetdalella.com\\\/fr\\\/vins-de-vendanges-tardives-naturellement-doux\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.bouquetdalella.com\\\/fr\\\/vins-de-vendanges-tardives-naturellement-doux\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.bouquetdalella.com\\\/fr\\\/vins-de-vendanges-tardives-naturellement-doux\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.bouquetdalella.com\\\/wp-content\\\/uploads\\\/2023\\\/04\\\/verema-bouquet-dalella.jpg\",\"contentUrl\":\"https:\\\/\\\/www.bouquetdalella.com\\\/wp-content\\\/uploads\\\/2023\\\/04\\\/verema-bouquet-dalella.jpg\",\"width\":768,\"height\":1024},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.bouquetdalella.com\\\/fr\\\/vins-de-vendanges-tardives-naturellement-doux\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inici\",\"item\":\"https:\\\/\\\/www.bouquetdalella.com\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Vins de vendanges tardives naturellement doux\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.bouquetdalella.com\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/www.bouquetdalella.com\\\/fr\\\/\",\"name\":\"Bouquet d&#039;Alella\",\"description\":\"El Celler Bouquet d\u2019Alella neix amb la clara intenci\u00f3 d\u2019explotar dues vessants diferents per\u00f2 complement\u00e0ries en el mon del vi. Per una banda, la producci\u00f3n i venda de vins ecol\u00f2gics de qualitat i per l\u2019altra la promoci\u00f3 de l\u2019enoturisme.\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.bouquetdalella.com\\\/fr\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.bouquetdalella.com\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.bouquetdalella.com\\\/fr\\\/#organization\",\"name\":\"Bouquet d&#039;Alella\",\"url\":\"https:\\\/\\\/www.bouquetdalella.com\\\/fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.bouquetdalella.com\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.bouquetdalella.com\\\/wp-content\\\/uploads\\\/2023\\\/04\\\/cropped-cropped-cropped-logo_bouquet_d_alella-2-300x53-1.png\",\"contentUrl\":\"https:\\\/\\\/www.bouquetdalella.com\\\/wp-content\\\/uploads\\\/2023\\\/04\\\/cropped-cropped-cropped-logo_bouquet_d_alella-2-300x53-1.png\",\"width\":300,\"height\":52,\"caption\":\"Bouquet d&#039;Alella\"},\"image\":{\"@id\":\"https:\\\/\\\/www.bouquetdalella.com\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.bouquetdalella.com\\\/fr\\\/#\\\/schema\\\/person\\\/726870fa22653a7029bc5a8074403803\",\"name\":\"Bouquet Alella\",\"sameAs\":[\"https:\\\/\\\/www.bouquetdalella.com\"],\"url\":\"https:\\\/\\\/www.bouquetdalella.com\\\/fr\\\/author\\\/soportebouquetdalella-com\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Vins de vendanges tardives naturellement doux - Bouquet d&#039;Alella","description":"Vins de vendanges tardives naturellement doux","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.bouquetdalella.com\/fr\/vins-de-vendanges-tardives-naturellement-doux\/","og_locale":"fr_FR","og_type":"article","og_title":"Vins de vendanges tardives naturellement doux - Bouquet d&#039;Alella","og_description":"Vins de vendanges tardives naturellement doux","og_url":"https:\/\/www.bouquetdalella.com\/fr\/vins-de-vendanges-tardives-naturellement-doux\/","og_site_name":"Bouquet d&#039;Alella","article_published_time":"2022-10-23T12:59:21+00:00","article_modified_time":"2022-10-23T13:05:10+00:00","og_image":[{"width":768,"height":1024,"url":"https:\/\/www.bouquetdalella.com\/wp-content\/uploads\/2023\/04\/verema-bouquet-dalella.jpg","type":"image\/jpeg"}],"author":"Bouquet Alella","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"Bouquet Alella","Dur\u00e9e de lecture estim\u00e9e":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.bouquetdalella.com\/fr\/vins-de-vendanges-tardives-naturellement-doux\/#article","isPartOf":{"@id":"https:\/\/www.bouquetdalella.com\/fr\/vins-de-vendanges-tardives-naturellement-doux\/"},"author":{"name":"Bouquet Alella","@id":"https:\/\/www.bouquetdalella.com\/fr\/#\/schema\/person\/726870fa22653a7029bc5a8074403803"},"headline":"Vins de vendanges tardives naturellement doux","datePublished":"2022-10-23T12:59:21+00:00","dateModified":"2022-10-23T13:05:10+00:00","mainEntityOfPage":{"@id":"https:\/\/www.bouquetdalella.com\/fr\/vins-de-vendanges-tardives-naturellement-doux\/"},"wordCount":138,"commentCount":0,"publisher":{"@id":"https:\/\/www.bouquetdalella.com\/fr\/#organization"},"image":{"@id":"https:\/\/www.bouquetdalella.com\/fr\/vins-de-vendanges-tardives-naturellement-doux\/#primaryimage"},"thumbnailUrl":"https:\/\/www.bouquetdalella.com\/wp-content\/uploads\/2023\/04\/verema-bouquet-dalella.jpg","articleSection":["Nouvelles"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.bouquetdalella.com\/fr\/vins-de-vendanges-tardives-naturellement-doux\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.bouquetdalella.com\/fr\/vins-de-vendanges-tardives-naturellement-doux\/","url":"https:\/\/www.bouquetdalella.com\/fr\/vins-de-vendanges-tardives-naturellement-doux\/","name":"Vins de vendanges tardives naturellement doux - Bouquet d&#039;Alella","isPartOf":{"@id":"https:\/\/www.bouquetdalella.com\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.bouquetdalella.com\/fr\/vins-de-vendanges-tardives-naturellement-doux\/#primaryimage"},"image":{"@id":"https:\/\/www.bouquetdalella.com\/fr\/vins-de-vendanges-tardives-naturellement-doux\/#primaryimage"},"thumbnailUrl":"https:\/\/www.bouquetdalella.com\/wp-content\/uploads\/2023\/04\/verema-bouquet-dalella.jpg","datePublished":"2022-10-23T12:59:21+00:00","dateModified":"2022-10-23T13:05:10+00:00","description":"Vins de vendanges tardives naturellement doux","breadcrumb":{"@id":"https:\/\/www.bouquetdalella.com\/fr\/vins-de-vendanges-tardives-naturellement-doux\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.bouquetdalella.com\/fr\/vins-de-vendanges-tardives-naturellement-doux\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.bouquetdalella.com\/fr\/vins-de-vendanges-tardives-naturellement-doux\/#primaryimage","url":"https:\/\/www.bouquetdalella.com\/wp-content\/uploads\/2023\/04\/verema-bouquet-dalella.jpg","contentUrl":"https:\/\/www.bouquetdalella.com\/wp-content\/uploads\/2023\/04\/verema-bouquet-dalella.jpg","width":768,"height":1024},{"@type":"BreadcrumbList","@id":"https:\/\/www.bouquetdalella.com\/fr\/vins-de-vendanges-tardives-naturellement-doux\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inici","item":"https:\/\/www.bouquetdalella.com\/fr\/"},{"@type":"ListItem","position":2,"name":"Vins de vendanges tardives naturellement doux"}]},{"@type":"WebSite","@id":"https:\/\/www.bouquetdalella.com\/fr\/#website","url":"https:\/\/www.bouquetdalella.com\/fr\/","name":"Bouquet d&#039;Alella","description":"El Celler Bouquet d\u2019Alella neix amb la clara intenci\u00f3 d\u2019explotar dues vessants diferents per\u00f2 complement\u00e0ries en el mon del vi. Per una banda, la producci\u00f3n i venda de vins ecol\u00f2gics de qualitat i per l\u2019altra la promoci\u00f3 de l\u2019enoturisme.","publisher":{"@id":"https:\/\/www.bouquetdalella.com\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.bouquetdalella.com\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/www.bouquetdalella.com\/fr\/#organization","name":"Bouquet d&#039;Alella","url":"https:\/\/www.bouquetdalella.com\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.bouquetdalella.com\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/www.bouquetdalella.com\/wp-content\/uploads\/2023\/04\/cropped-cropped-cropped-logo_bouquet_d_alella-2-300x53-1.png","contentUrl":"https:\/\/www.bouquetdalella.com\/wp-content\/uploads\/2023\/04\/cropped-cropped-cropped-logo_bouquet_d_alella-2-300x53-1.png","width":300,"height":52,"caption":"Bouquet d&#039;Alella"},"image":{"@id":"https:\/\/www.bouquetdalella.com\/fr\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/www.bouquetdalella.com\/fr\/#\/schema\/person\/726870fa22653a7029bc5a8074403803","name":"Bouquet Alella","sameAs":["https:\/\/www.bouquetdalella.com"],"url":"https:\/\/www.bouquetdalella.com\/fr\/author\/soportebouquetdalella-com\/"}]}},"_links":{"self":[{"href":"https:\/\/www.bouquetdalella.com\/fr\/wp-json\/wp\/v2\/posts\/13030","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.bouquetdalella.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.bouquetdalella.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.bouquetdalella.com\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.bouquetdalella.com\/fr\/wp-json\/wp\/v2\/comments?post=13030"}],"version-history":[{"count":0,"href":"https:\/\/www.bouquetdalella.com\/fr\/wp-json\/wp\/v2\/posts\/13030\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.bouquetdalella.com\/fr\/wp-json\/wp\/v2\/media\/6266"}],"wp:attachment":[{"href":"https:\/\/www.bouquetdalella.com\/fr\/wp-json\/wp\/v2\/media?parent=13030"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.bouquetdalella.com\/fr\/wp-json\/wp\/v2\/categories?post=13030"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.bouquetdalella.com\/fr\/wp-json\/wp\/v2\/tags?post=13030"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}