{"id":13045,"date":"2022-11-11T14:48:24","date_gmt":"2022-11-11T13:48:24","guid":{"rendered":"https:\/\/www.bouquetdalella.com\/yoga-entre-vignes\/"},"modified":"2022-11-11T14:57:23","modified_gmt":"2022-11-11T13:57:23","slug":"yoga-entre-vignes","status":"publish","type":"post","link":"https:\/\/www.bouquetdalella.com\/fr\/yoga-entre-vignes\/","title":{"rendered":"Yoga entre vignes"},"content":{"rendered":"<p>Offrez-vous une matin\u00e9e de bien-\u00eatre, en prenant soin de votre corps et en profitant de la nature. Nous vous attendons le samedi 19 novembre \u00e0 10h pour une s\u00e9ance de yoga entre vignes. Tu ne peux pas rater \u00e7a!!!<br \/>\nr\u00e9servez votre place sur ce lien https:\/\/www.bouquetdalella.com\/producte\/ioga-entre-vinyes\/<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Offrez-vous une matin\u00e9e de bien-\u00eatre, en prenant soin de votre corps et en profitant de la nature. Nous vous attendons le samedi 19 novembre \u00e0 10h pour une s\u00e9ance de yoga entre vignes. Tu ne peux pas rater \u00e7a!!! r\u00e9servez votre place sur ce lien https:\/\/www.bouquetdalella.com\/producte\/ioga-entre-vinyes\/ &nbsp;<\/p>\n","protected":false},"author":1,"featured_media":6272,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[189],"tags":[],"class_list":["post-13045","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-nouvelles"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Yoga entre vignes - Bouquet d&#039;Alella<\/title>\n<meta name=\"description\" content=\"yoga entre vignes\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.bouquetdalella.com\/fr\/yoga-entre-vignes\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Yoga entre vignes - Bouquet d&#039;Alella\" \/>\n<meta property=\"og:description\" content=\"yoga entre vignes\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.bouquetdalella.com\/fr\/yoga-entre-vignes\/\" \/>\n<meta property=\"og:site_name\" content=\"Bouquet d&#039;Alella\" \/>\n<meta property=\"article:published_time\" content=\"2022-11-11T13:48:24+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-11-11T13:57:23+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.bouquetdalella.com\/wp-content\/uploads\/2023\/04\/IOGA-ENTRE-VINYES.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1080\" \/>\n\t<meta property=\"og:image:height\" content=\"1080\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Bouquet Alella\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Bouquet Alella\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.bouquetdalella.com\\\/fr\\\/yoga-entre-vignes\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.bouquetdalella.com\\\/fr\\\/yoga-entre-vignes\\\/\"},\"author\":{\"name\":\"Bouquet Alella\",\"@id\":\"https:\\\/\\\/www.bouquetdalella.com\\\/fr\\\/#\\\/schema\\\/person\\\/726870fa22653a7029bc5a8074403803\"},\"headline\":\"Yoga entre vignes\",\"datePublished\":\"2022-11-11T13:48:24+00:00\",\"dateModified\":\"2022-11-11T13:57:23+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.bouquetdalella.com\\\/fr\\\/yoga-entre-vignes\\\/\"},\"wordCount\":57,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.bouquetdalella.com\\\/fr\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.bouquetdalella.com\\\/fr\\\/yoga-entre-vignes\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.bouquetdalella.com\\\/wp-content\\\/uploads\\\/2023\\\/04\\\/IOGA-ENTRE-VINYES.jpg\",\"articleSection\":[\"Nouvelles\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.bouquetdalella.com\\\/fr\\\/yoga-entre-vignes\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.bouquetdalella.com\\\/fr\\\/yoga-entre-vignes\\\/\",\"url\":\"https:\\\/\\\/www.bouquetdalella.com\\\/fr\\\/yoga-entre-vignes\\\/\",\"name\":\"Yoga entre vignes - Bouquet d&#039;Alella\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.bouquetdalella.com\\\/fr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.bouquetdalella.com\\\/fr\\\/yoga-entre-vignes\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.bouquetdalella.com\\\/fr\\\/yoga-entre-vignes\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.bouquetdalella.com\\\/wp-content\\\/uploads\\\/2023\\\/04\\\/IOGA-ENTRE-VINYES.jpg\",\"datePublished\":\"2022-11-11T13:48:24+00:00\",\"dateModified\":\"2022-11-11T13:57:23+00:00\",\"description\":\"yoga entre vignes\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.bouquetdalella.com\\\/fr\\\/yoga-entre-vignes\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.bouquetdalella.com\\\/fr\\\/yoga-entre-vignes\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.bouquetdalella.com\\\/fr\\\/yoga-entre-vignes\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.bouquetdalella.com\\\/wp-content\\\/uploads\\\/2023\\\/04\\\/IOGA-ENTRE-VINYES.jpg\",\"contentUrl\":\"https:\\\/\\\/www.bouquetdalella.com\\\/wp-content\\\/uploads\\\/2023\\\/04\\\/IOGA-ENTRE-VINYES.jpg\",\"width\":1080,\"height\":1080},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.bouquetdalella.com\\\/fr\\\/yoga-entre-vignes\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inici\",\"item\":\"https:\\\/\\\/www.bouquetdalella.com\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Yoga entre vignes\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.bouquetdalella.com\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/www.bouquetdalella.com\\\/fr\\\/\",\"name\":\"Bouquet d&#039;Alella\",\"description\":\"El Celler Bouquet d\u2019Alella neix amb la clara intenci\u00f3 d\u2019explotar dues vessants diferents per\u00f2 complement\u00e0ries en el mon del vi. Per una banda, la producci\u00f3n i venda de vins ecol\u00f2gics de qualitat i per l\u2019altra la promoci\u00f3 de l\u2019enoturisme.\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.bouquetdalella.com\\\/fr\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.bouquetdalella.com\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.bouquetdalella.com\\\/fr\\\/#organization\",\"name\":\"Bouquet d&#039;Alella\",\"url\":\"https:\\\/\\\/www.bouquetdalella.com\\\/fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.bouquetdalella.com\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.bouquetdalella.com\\\/wp-content\\\/uploads\\\/2023\\\/04\\\/cropped-cropped-cropped-logo_bouquet_d_alella-2-300x53-1.png\",\"contentUrl\":\"https:\\\/\\\/www.bouquetdalella.com\\\/wp-content\\\/uploads\\\/2023\\\/04\\\/cropped-cropped-cropped-logo_bouquet_d_alella-2-300x53-1.png\",\"width\":300,\"height\":52,\"caption\":\"Bouquet d&#039;Alella\"},\"image\":{\"@id\":\"https:\\\/\\\/www.bouquetdalella.com\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.bouquetdalella.com\\\/fr\\\/#\\\/schema\\\/person\\\/726870fa22653a7029bc5a8074403803\",\"name\":\"Bouquet Alella\",\"sameAs\":[\"https:\\\/\\\/www.bouquetdalella.com\"],\"url\":\"https:\\\/\\\/www.bouquetdalella.com\\\/fr\\\/author\\\/soportebouquetdalella-com\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Yoga entre vignes - Bouquet d&#039;Alella","description":"yoga entre vignes","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.bouquetdalella.com\/fr\/yoga-entre-vignes\/","og_locale":"fr_FR","og_type":"article","og_title":"Yoga entre vignes - Bouquet d&#039;Alella","og_description":"yoga entre vignes","og_url":"https:\/\/www.bouquetdalella.com\/fr\/yoga-entre-vignes\/","og_site_name":"Bouquet d&#039;Alella","article_published_time":"2022-11-11T13:48:24+00:00","article_modified_time":"2022-11-11T13:57:23+00:00","og_image":[{"width":1080,"height":1080,"url":"https:\/\/www.bouquetdalella.com\/wp-content\/uploads\/2023\/04\/IOGA-ENTRE-VINYES.jpg","type":"image\/jpeg"}],"author":"Bouquet Alella","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"Bouquet Alella","Dur\u00e9e de lecture estim\u00e9e":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.bouquetdalella.com\/fr\/yoga-entre-vignes\/#article","isPartOf":{"@id":"https:\/\/www.bouquetdalella.com\/fr\/yoga-entre-vignes\/"},"author":{"name":"Bouquet Alella","@id":"https:\/\/www.bouquetdalella.com\/fr\/#\/schema\/person\/726870fa22653a7029bc5a8074403803"},"headline":"Yoga entre vignes","datePublished":"2022-11-11T13:48:24+00:00","dateModified":"2022-11-11T13:57:23+00:00","mainEntityOfPage":{"@id":"https:\/\/www.bouquetdalella.com\/fr\/yoga-entre-vignes\/"},"wordCount":57,"commentCount":0,"publisher":{"@id":"https:\/\/www.bouquetdalella.com\/fr\/#organization"},"image":{"@id":"https:\/\/www.bouquetdalella.com\/fr\/yoga-entre-vignes\/#primaryimage"},"thumbnailUrl":"https:\/\/www.bouquetdalella.com\/wp-content\/uploads\/2023\/04\/IOGA-ENTRE-VINYES.jpg","articleSection":["Nouvelles"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.bouquetdalella.com\/fr\/yoga-entre-vignes\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.bouquetdalella.com\/fr\/yoga-entre-vignes\/","url":"https:\/\/www.bouquetdalella.com\/fr\/yoga-entre-vignes\/","name":"Yoga entre vignes - Bouquet d&#039;Alella","isPartOf":{"@id":"https:\/\/www.bouquetdalella.com\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.bouquetdalella.com\/fr\/yoga-entre-vignes\/#primaryimage"},"image":{"@id":"https:\/\/www.bouquetdalella.com\/fr\/yoga-entre-vignes\/#primaryimage"},"thumbnailUrl":"https:\/\/www.bouquetdalella.com\/wp-content\/uploads\/2023\/04\/IOGA-ENTRE-VINYES.jpg","datePublished":"2022-11-11T13:48:24+00:00","dateModified":"2022-11-11T13:57:23+00:00","description":"yoga entre vignes","breadcrumb":{"@id":"https:\/\/www.bouquetdalella.com\/fr\/yoga-entre-vignes\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.bouquetdalella.com\/fr\/yoga-entre-vignes\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.bouquetdalella.com\/fr\/yoga-entre-vignes\/#primaryimage","url":"https:\/\/www.bouquetdalella.com\/wp-content\/uploads\/2023\/04\/IOGA-ENTRE-VINYES.jpg","contentUrl":"https:\/\/www.bouquetdalella.com\/wp-content\/uploads\/2023\/04\/IOGA-ENTRE-VINYES.jpg","width":1080,"height":1080},{"@type":"BreadcrumbList","@id":"https:\/\/www.bouquetdalella.com\/fr\/yoga-entre-vignes\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inici","item":"https:\/\/www.bouquetdalella.com\/fr\/"},{"@type":"ListItem","position":2,"name":"Yoga entre vignes"}]},{"@type":"WebSite","@id":"https:\/\/www.bouquetdalella.com\/fr\/#website","url":"https:\/\/www.bouquetdalella.com\/fr\/","name":"Bouquet d&#039;Alella","description":"El Celler Bouquet d\u2019Alella neix amb la clara intenci\u00f3 d\u2019explotar dues vessants diferents per\u00f2 complement\u00e0ries en el mon del vi. Per una banda, la producci\u00f3n i venda de vins ecol\u00f2gics de qualitat i per l\u2019altra la promoci\u00f3 de l\u2019enoturisme.","publisher":{"@id":"https:\/\/www.bouquetdalella.com\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.bouquetdalella.com\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/www.bouquetdalella.com\/fr\/#organization","name":"Bouquet d&#039;Alella","url":"https:\/\/www.bouquetdalella.com\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.bouquetdalella.com\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/www.bouquetdalella.com\/wp-content\/uploads\/2023\/04\/cropped-cropped-cropped-logo_bouquet_d_alella-2-300x53-1.png","contentUrl":"https:\/\/www.bouquetdalella.com\/wp-content\/uploads\/2023\/04\/cropped-cropped-cropped-logo_bouquet_d_alella-2-300x53-1.png","width":300,"height":52,"caption":"Bouquet d&#039;Alella"},"image":{"@id":"https:\/\/www.bouquetdalella.com\/fr\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/www.bouquetdalella.com\/fr\/#\/schema\/person\/726870fa22653a7029bc5a8074403803","name":"Bouquet Alella","sameAs":["https:\/\/www.bouquetdalella.com"],"url":"https:\/\/www.bouquetdalella.com\/fr\/author\/soportebouquetdalella-com\/"}]}},"_links":{"self":[{"href":"https:\/\/www.bouquetdalella.com\/fr\/wp-json\/wp\/v2\/posts\/13045","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.bouquetdalella.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.bouquetdalella.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.bouquetdalella.com\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.bouquetdalella.com\/fr\/wp-json\/wp\/v2\/comments?post=13045"}],"version-history":[{"count":0,"href":"https:\/\/www.bouquetdalella.com\/fr\/wp-json\/wp\/v2\/posts\/13045\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.bouquetdalella.com\/fr\/wp-json\/wp\/v2\/media\/6272"}],"wp:attachment":[{"href":"https:\/\/www.bouquetdalella.com\/fr\/wp-json\/wp\/v2\/media?parent=13045"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.bouquetdalella.com\/fr\/wp-json\/wp\/v2\/categories?post=13045"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.bouquetdalella.com\/fr\/wp-json\/wp\/v2\/tags?post=13045"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}